{"id":3973,"date":"2011-02-02T09:54:38","date_gmt":"2011-02-02T09:54:38","guid":{"rendered":""},"modified":"2011-02-28T09:11:14","modified_gmt":"2011-02-28T09:11:14","slug":"vinn-resident-evil-afterlife","status":"publish","type":"post","link":"https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/","title":{"rendered":"Vinn \u00abResident Evil: Afterlife\u00bb"},"content":{"rendered":"<p><em>Vinnerne er trukket: IIIIsNIIII, projectD og Doffy f\u00e5r filmen tilsendt i posten.<\/em><\/p>\n<p>Er du stor fan av \u00abResident Evil\u00bb-serien? Da kjenner du sikkert til filmene basert p\u00e5 spillet. \u00abResident Evil: Afterlife\u00bb er den fjerde filmen i serien, og her dukker kjente spillfigurer som Chris og Claire Redfield, Albert Wesker og Jill Valentine opp.<\/p>\n<h5>Fem filmer<\/h5>\n<p>Vi deler ut fem filmer til fem heldige vinnere, som kan velge om de vil ha filmen p\u00e5 blu-ray eller DVD. Alt du trenger \u00e5 gj\u00f8re for \u00e5 bli med i konkurransen er \u00e5 svare riktig p\u00e5 sp\u00f8rsm\u00e5let under. Konkurransen avsluttes 10. februar. Lykke til!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vi deler ut film p\u00e5 blu-ray og DVD.<\/p>\n","protected":false},"author":196477,"featured_media":9945,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[2369,3623,5460],"class_list":["post-3973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-film","tag-konkurranse","tag-resident-evil"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vinn \u00abResident Evil: Afterlife\u00bb - Spill.no<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vinn \u00abResident Evil: Afterlife\u00bb - Spill.no\" \/>\n<meta property=\"og:description\" content=\"Vi deler ut film p\u00e5 blu-ray og DVD.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/\" \/>\n<meta property=\"og:site_name\" content=\"Spill.no\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/spillno\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-02T09:54:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2011-02-28T09:11:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spill.no\/wp-content\/uploads\/2018\/06\/nocat-e1527687117518.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"817\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Spill.no\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@spillno\" \/>\n<meta name=\"twitter:site\" content=\"@spillno\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Spill.no\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/vinn-resident-evil-afterlife\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/vinn-resident-evil-afterlife\\\/\"},\"author\":{\"name\":\"Spill.no\",\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/#\\\/schema\\\/person\\\/2e44e17042e43f27c8b583621a2eff76\"},\"headline\":\"Vinn \u00abResident Evil: Afterlife\u00bb\",\"datePublished\":\"2011-02-02T09:54:38+00:00\",\"dateModified\":\"2011-02-28T09:11:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/vinn-resident-evil-afterlife\\\/\"},\"wordCount\":105,\"publisher\":{\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/vinn-resident-evil-afterlife\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spill.no\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/nocat-e1527687117518.jpg\",\"keywords\":[\"Film\",\"konkurranse\",\"Resident Evil\"],\"articleSection\":[\"Uncategorized @\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/vinn-resident-evil-afterlife\\\/\",\"url\":\"https:\\\/\\\/spill.no\\\/en\\\/vinn-resident-evil-afterlife\\\/\",\"name\":\"Vinn \u00abResident Evil: Afterlife\u00bb - Spill.no\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/vinn-resident-evil-afterlife\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/vinn-resident-evil-afterlife\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spill.no\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/nocat-e1527687117518.jpg\",\"datePublished\":\"2011-02-02T09:54:38+00:00\",\"dateModified\":\"2011-02-28T09:11:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/vinn-resident-evil-afterlife\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spill.no\\\/en\\\/vinn-resident-evil-afterlife\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/vinn-resident-evil-afterlife\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spill.no\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/nocat-e1527687117518.jpg\",\"contentUrl\":\"https:\\\/\\\/spill.no\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/nocat-e1527687117518.jpg\",\"width\":817,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/vinn-resident-evil-afterlife\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/spill.no\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vinn \u00abResident Evil: Afterlife\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/spill.no\\\/en\\\/\",\"name\":\"Spill.no\",\"description\":\"Spillnyheter, anmeldelser og spill-community\",\"publisher\":{\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spill.no\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/#organization\",\"name\":\"Spill.no\",\"url\":\"https:\\\/\\\/spill.no\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/spill.no\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/spill.png\",\"contentUrl\":\"https:\\\/\\\/spill.no\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/spill.png\",\"width\":251,\"height\":68,\"caption\":\"Spill.no\"},\"image\":{\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/spillno\",\"https:\\\/\\\/x.com\\\/spillno\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spill.no\\\/en\\\/#\\\/schema\\\/person\\\/2e44e17042e43f27c8b583621a2eff76\",\"name\":\"Spill.no\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d63c5cec3fa425ca1bca771136cb5005d976152339b81304d38b0f3e8a5b053?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d63c5cec3fa425ca1bca771136cb5005d976152339b81304d38b0f3e8a5b053?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d63c5cec3fa425ca1bca771136cb5005d976152339b81304d38b0f3e8a5b053?s=96&d=blank&r=g\",\"caption\":\"Spill.no\"},\"description\":\"Spill.no ble stiftet i 2009 og har siden oppstarten utviklet seg til \u00e5 bli Norges st\u00f8rste uavhengige spillnettside. P\u00e5 Spill.no kan du lese spillnyheter, anmeldelser og mer om spill til Playstation, Xbox, Nintendo, PC, mobil og andre plattformer.\",\"sameAs\":[\"https:\\\/\\\/spill.no\"],\"url\":\"https:\\\/\\\/spill.no\\\/en\\\/author\\\/spill-no\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vinn \u00abResident Evil: Afterlife\u00bb - Spill.no","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/","og_locale":"en_US","og_type":"article","og_title":"Vinn \u00abResident Evil: Afterlife\u00bb - Spill.no","og_description":"Vi deler ut film p\u00e5 blu-ray og DVD.","og_url":"https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/","og_site_name":"Spill.no","article_publisher":"https:\/\/facebook.com\/spillno","article_published_time":"2011-02-02T09:54:38+00:00","article_modified_time":"2011-02-28T09:11:14+00:00","og_image":[{"width":817,"height":320,"url":"https:\/\/spill.no\/wp-content\/uploads\/2018\/06\/nocat-e1527687117518.jpg","type":"image\/jpeg"}],"author":"Spill.no","twitter_card":"summary_large_image","twitter_creator":"@spillno","twitter_site":"@spillno","twitter_misc":{"Written by":"Spill.no","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/#article","isPartOf":{"@id":"https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/"},"author":{"name":"Spill.no","@id":"https:\/\/spill.no\/en\/#\/schema\/person\/2e44e17042e43f27c8b583621a2eff76"},"headline":"Vinn \u00abResident Evil: Afterlife\u00bb","datePublished":"2011-02-02T09:54:38+00:00","dateModified":"2011-02-28T09:11:14+00:00","mainEntityOfPage":{"@id":"https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/"},"wordCount":105,"publisher":{"@id":"https:\/\/spill.no\/en\/#organization"},"image":{"@id":"https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/#primaryimage"},"thumbnailUrl":"https:\/\/spill.no\/wp-content\/uploads\/2018\/06\/nocat-e1527687117518.jpg","keywords":["Film","konkurranse","Resident Evil"],"articleSection":["Uncategorized @"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/","url":"https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/","name":"Vinn \u00abResident Evil: Afterlife\u00bb - Spill.no","isPartOf":{"@id":"https:\/\/spill.no\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/#primaryimage"},"image":{"@id":"https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/#primaryimage"},"thumbnailUrl":"https:\/\/spill.no\/wp-content\/uploads\/2018\/06\/nocat-e1527687117518.jpg","datePublished":"2011-02-02T09:54:38+00:00","dateModified":"2011-02-28T09:11:14+00:00","breadcrumb":{"@id":"https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/#primaryimage","url":"https:\/\/spill.no\/wp-content\/uploads\/2018\/06\/nocat-e1527687117518.jpg","contentUrl":"https:\/\/spill.no\/wp-content\/uploads\/2018\/06\/nocat-e1527687117518.jpg","width":817,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/spill.no\/en\/vinn-resident-evil-afterlife\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/spill.no\/en\/"},{"@type":"ListItem","position":2,"name":"Vinn \u00abResident Evil: Afterlife\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/spill.no\/en\/#website","url":"https:\/\/spill.no\/en\/","name":"Spill.no","description":"Spillnyheter, anmeldelser og spill-community","publisher":{"@id":"https:\/\/spill.no\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spill.no\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/spill.no\/en\/#organization","name":"Spill.no","url":"https:\/\/spill.no\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/spill.no\/en\/#\/schema\/logo\/image\/","url":"https:\/\/spill.no\/wp-content\/uploads\/2014\/02\/spill.png","contentUrl":"https:\/\/spill.no\/wp-content\/uploads\/2014\/02\/spill.png","width":251,"height":68,"caption":"Spill.no"},"image":{"@id":"https:\/\/spill.no\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/spillno","https:\/\/x.com\/spillno"]},{"@type":"Person","@id":"https:\/\/spill.no\/en\/#\/schema\/person\/2e44e17042e43f27c8b583621a2eff76","name":"Spill.no","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/0d63c5cec3fa425ca1bca771136cb5005d976152339b81304d38b0f3e8a5b053?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0d63c5cec3fa425ca1bca771136cb5005d976152339b81304d38b0f3e8a5b053?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0d63c5cec3fa425ca1bca771136cb5005d976152339b81304d38b0f3e8a5b053?s=96&d=blank&r=g","caption":"Spill.no"},"description":"Spill.no ble stiftet i 2009 og har siden oppstarten utviklet seg til \u00e5 bli Norges st\u00f8rste uavhengige spillnettside. P\u00e5 Spill.no kan du lese spillnyheter, anmeldelser og mer om spill til Playstation, Xbox, Nintendo, PC, mobil og andre plattformer.","sameAs":["https:\/\/spill.no"],"url":"https:\/\/spill.no\/en\/author\/spill-no\/"}]}},"_links":{"self":[{"href":"https:\/\/spill.no\/en\/wp-json\/wp\/v2\/posts\/3973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spill.no\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spill.no\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spill.no\/en\/wp-json\/wp\/v2\/users\/196477"}],"replies":[{"embeddable":true,"href":"https:\/\/spill.no\/en\/wp-json\/wp\/v2\/comments?post=3973"}],"version-history":[{"count":0,"href":"https:\/\/spill.no\/en\/wp-json\/wp\/v2\/posts\/3973\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spill.no\/en\/wp-json\/wp\/v2\/media\/9945"}],"wp:attachment":[{"href":"https:\/\/spill.no\/en\/wp-json\/wp\/v2\/media?parent=3973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spill.no\/en\/wp-json\/wp\/v2\/categories?post=3973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spill.no\/en\/wp-json\/wp\/v2\/tags?post=3973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}